{"id":1530,"date":"2017-02-10T07:18:52","date_gmt":"2017-02-10T07:18:52","guid":{"rendered":"http:\/\/consult.loc\/?page_id=1519"},"modified":"2017-02-10T07:18:52","modified_gmt":"2017-02-10T07:18:52","slug":"events-grid","status":"publish","type":"page","link":"https:\/\/www.amchambaq.com\/es_co\/events-grid\/","title":{"rendered":"Events Grid"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1483614678807\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner \"><div class=\"wpb_wrapper\">\n            <div class=\"stm_events_grid cols_3\">\n            \n                <div class=\"item\">\n    <div class=\"item_wr\">\n                                <div class=\"item_thumbnail\">\n                <a href=\"https:\/\/www.amchambaq.com\/es_co\/events\/torneo-anual-de-golf-amcham\/\">\n                    <img decoding=\"async\" class=\"\" src=\"https:\/\/www.amchambaq.com\/wp-content\/uploads\/2021\/09\/FOTO-TORNEO-scaled-700x390.jpg\" width=\"700\" height=\"390\" alt=\"FOTO-TORNEO\" title=\"FOTO-TORNEO\" loading=\"lazy\" \/>                <\/a>\n            <\/div>\n                <div class=\"content\">\n            <h6><a href=\"https:\/\/www.amchambaq.com\/es_co\/events\/torneo-anual-de-golf-amcham\/\">Torneo Anual de Golf Amcham<\/a><\/h6>\n            <ul class=\"stm-event__meta\">\n                                                   <li>\n                       <div class=\"event__calendar\">\n                            <i class=\"fa fa-calendar\" aria-hidden=\"true\"><\/i> mayo 28, 2021                        <\/div>\n                    <\/li>\n                                                                                                                    <\/ul>\n        <\/div>\n    <\/div>\n<\/div>\n            \n                <div class=\"item\">\n    <div class=\"item_wr\">\n                                <div class=\"item_thumbnail\">\n                <a href=\"https:\/\/www.amchambaq.com\/es_co\/events\/asamblea-general-de-afiliados\/\">\n                    <img decoding=\"async\" class=\"\" src=\"https:\/\/www.amchambaq.com\/wp-content\/uploads\/2021\/09\/Personalidades-2-1-700x390.jpg\" width=\"700\" height=\"390\" alt=\"Personalidades 2\" title=\"Personalidades 2\" loading=\"lazy\" \/>                <\/a>\n            <\/div>\n                <div class=\"content\">\n            <h6><a href=\"https:\/\/www.amchambaq.com\/es_co\/events\/asamblea-general-de-afiliados\/\">Asamblea General de Afiliados<\/a><\/h6>\n            <ul class=\"stm-event__meta\">\n                                                   <li>\n                       <div class=\"event__calendar\">\n                            <i class=\"fa fa-calendar\" aria-hidden=\"true\"><\/i> mayo 28, 2021                        <\/div>\n                    <\/li>\n                                                                                                                    <\/ul>\n        <\/div>\n    <\/div>\n<\/div>\n            \n                <div class=\"item\">\n    <div class=\"item_wr\">\n                                <div class=\"item_thumbnail\">\n                <a href=\"https:\/\/www.amchambaq.com\/es_co\/events\/dia-de-accion-de-gracias\/\">\n                    <img decoding=\"async\" class=\"\" src=\"https:\/\/www.amchambaq.com\/wp-content\/uploads\/2021\/05\/WEB-scaled-700x390.jpg\" width=\"700\" height=\"390\" alt=\"WEB\" title=\"WEB\" loading=\"lazy\" \/>                <\/a>\n            <\/div>\n                <div class=\"content\">\n            <h6><a href=\"https:\/\/www.amchambaq.com\/es_co\/events\/dia-de-accion-de-gracias\/\">D\u00eda de Acci\u00f3n de Gracias<\/a><\/h6>\n            <ul class=\"stm-event__meta\">\n                                                   <li>\n                       <div class=\"event__calendar\">\n                            <i class=\"fa fa-calendar\" aria-hidden=\"true\"><\/i> mayo 28, 2021                        <\/div>\n                    <\/li>\n                                                                                                                    <\/ul>\n        <\/div>\n    <\/div>\n<\/div>\n            \n                <div class=\"item\">\n    <div class=\"item_wr\">\n                                <div class=\"item_thumbnail\">\n                <a href=\"https:\/\/www.amchambaq.com\/es_co\/events\/congreso-de-seguridad\/\">\n                    <img decoding=\"async\" class=\"\" src=\"https:\/\/www.amchambaq.com\/wp-content\/uploads\/2021\/09\/FOTO-CONGRESO-SEGURIDAD-scaled-700x390.jpg\" width=\"700\" height=\"390\" alt=\"FOTO-CONGRESO-SEGURIDAD\" title=\"FOTO-CONGRESO-SEGURIDAD\" loading=\"lazy\" \/>                <\/a>\n            <\/div>\n                <div class=\"content\">\n            <h6><a href=\"https:\/\/www.amchambaq.com\/es_co\/events\/congreso-de-seguridad\/\">Congreso de Seguridad<\/a><\/h6>\n            <ul class=\"stm-event__meta\">\n                                                   <li>\n                       <div class=\"event__calendar\">\n                            <i class=\"fa fa-calendar\" aria-hidden=\"true\"><\/i> mayo 28, 2021                        <\/div>\n                    <\/li>\n                                                                                                                    <\/ul>\n        <\/div>\n    <\/div>\n<\/div>\n            \n                <div class=\"item\">\n    <div class=\"item_wr\">\n                                <div class=\"item_thumbnail\">\n                <a href=\"https:\/\/www.amchambaq.com\/es_co\/events\/errores-frecuentes-en-la-informacion-exogena-y-reduccion-de-sanciones-e-intereses-en-virtud-de-la-ley-2155-de-2021\/\">\n                    <img decoding=\"async\" class=\"\" src=\"https:\/\/www.amchambaq.com\/wp-content\/uploads\/2021\/11\/02_diciembre_2021-1-700x390.jpg\" width=\"700\" height=\"390\" alt=\"02_diciembre_2021 (1)\" title=\"02_diciembre_2021 (1)\" loading=\"lazy\" \/>                <\/a>\n            <\/div>\n                <div class=\"content\">\n            <h6><a href=\"https:\/\/www.amchambaq.com\/es_co\/events\/errores-frecuentes-en-la-informacion-exogena-y-reduccion-de-sanciones-e-intereses-en-virtud-de-la-ley-2155-de-2021\/\">Errores frecuentes en la informaci\u00f3n ex\u00f3gena y reducci\u00f3n de sanciones e intereses en virtud de la Ley  2155 de 2021<\/a><\/h6>\n            <ul class=\"stm-event__meta\">\n                                                   <li>\n                       <div class=\"event__calendar\">\n                            <i class=\"fa fa-calendar\" aria-hidden=\"true\"><\/i> diciembre 2, 2021                        <\/div>\n                    <\/li>\n                                                                                                <li>\n                            <div class=\"event__time\"><i class=\"fa fa-clock-o\"><\/i>\n                                2:00 pm to 3:00 pm                            <\/div>\n                        <\/li>\n                                                                        <li>\n                        <div class=\"event__venue\">\n                            <i class=\"fa fa-map-marker\" aria-hidden=\"true\"><\/i> Barranquilla                        <\/div>\n                    <\/li>\n                            <\/ul>\n        <\/div>\n    <\/div>\n<\/div>\n            \n                <div class=\"item\">\n    <div class=\"item_wr\">\n                                <div class=\"item_thumbnail\">\n                <a href=\"https:\/\/www.amchambaq.com\/es_co\/events\/amcham-golf-tournament-2024\/\">\n                    <img decoding=\"async\" class=\"\" src=\"https:\/\/www.amchambaq.com\/wp-content\/uploads\/2024\/04\/TORNEO-DE-GOLF-2024-AMCHAM-Post-de-Instagram-700x390.jpg\" width=\"700\" height=\"390\" alt=\"TORNEO DE GOLF 2024 AMCHAM (Post de Instagram)\" title=\"TORNEO DE GOLF 2024 AMCHAM (Post de Instagram)\" loading=\"lazy\" \/>                <\/a>\n            <\/div>\n                <div class=\"content\">\n            <h6><a href=\"https:\/\/www.amchambaq.com\/es_co\/events\/amcham-golf-tournament-2024\/\">AmCham Golf Tournament 2024<\/a><\/h6>\n            <ul class=\"stm-event__meta\">\n                                                   <li>\n                       <div class=\"event__calendar\">\n                            <i class=\"fa fa-calendar\" aria-hidden=\"true\"><\/i> junio 7, 2024                        <\/div>\n                    <\/li>\n                                                                                                <li>\n                            <div class=\"event__time\"><i class=\"fa fa-clock-o\"><\/i>\n                                6:00 am to 1:00 pm                            <\/div>\n                        <\/li>\n                                                                        <li>\n                        <div class=\"event__venue\">\n                            <i class=\"fa fa-map-marker\" aria-hidden=\"true\"><\/i> Barranquilla                        <\/div>\n                    <\/li>\n                            <\/ul>\n        <\/div>\n    <\/div>\n<\/div>\n            \n                <div class=\"item\">\n    <div class=\"item_wr\">\n                                <div class=\"item_thumbnail\">\n                <a href=\"https:\/\/www.amchambaq.com\/es_co\/events\/comite-tributario-amcham-2\/\">\n                    <img decoding=\"async\" class=\"\" src=\"https:\/\/www.amchambaq.com\/wp-content\/uploads\/2025\/05\/niif-nov-1-700x390.png\" width=\"700\" height=\"390\" alt=\"niif nov (1)\" title=\"niif nov (1)\" loading=\"lazy\" \/>                <\/a>\n            <\/div>\n                <div class=\"content\">\n            <h6><a href=\"https:\/\/www.amchambaq.com\/es_co\/events\/comite-tributario-amcham-2\/\">Comit\u00e9 NIIF<\/a><\/h6>\n            <ul class=\"stm-event__meta\">\n                                                   <li>\n                       <div class=\"event__calendar\">\n                            <i class=\"fa fa-calendar\" aria-hidden=\"true\"><\/i> noviembre 27, 2025                        <\/div>\n                    <\/li>\n                                                                                                <li>\n                            <div class=\"event__time\"><i class=\"fa fa-clock-o\"><\/i>\n                                8:00 am to 10:00 am                            <\/div>\n                        <\/li>\n                                                                        <li>\n                        <div class=\"event__venue\">\n                            <i class=\"fa fa-map-marker\" aria-hidden=\"true\"><\/i> Barranquilla                        <\/div>\n                    <\/li>\n                            <\/ul>\n        <\/div>\n    <\/div>\n<\/div>\n            \n                <div class=\"item\">\n    <div class=\"item_wr\">\n                                <div class=\"item_thumbnail\">\n                <a href=\"https:\/\/www.amchambaq.com\/es_co\/events\/receso-amcham-team-por-festividades\/\">\n                    <img decoding=\"async\" class=\"\" src=\"https:\/\/www.amchambaq.com\/wp-content\/uploads\/2025\/08\/vacaciones-colectivas-2024-700x390.jpg\" width=\"700\" height=\"390\" alt=\"vacaciones colectivas 2024\" title=\"vacaciones colectivas 2024\" loading=\"lazy\" \/>                <\/a>\n            <\/div>\n                <div class=\"content\">\n            <h6><a href=\"https:\/\/www.amchambaq.com\/es_co\/events\/receso-amcham-team-por-festividades\/\">Receso AmCham Team por festividades<\/a><\/h6>\n            <ul class=\"stm-event__meta\">\n                                                   <li>\n                       <div class=\"event__calendar\">\n                            <i class=\"fa fa-calendar\" aria-hidden=\"true\"><\/i> diciembre 22, 2025                        <\/div>\n                    <\/li>\n                                                                                                <li>\n                            <div class=\"event__time\"><i class=\"fa fa-clock-o\"><\/i>\n                                8:00 am to 5:00 pm                            <\/div>\n                        <\/li>\n                                                                        <li>\n                        <div class=\"event__venue\">\n                            <i class=\"fa fa-map-marker\" aria-hidden=\"true\"><\/i> Barranquilla                        <\/div>\n                    <\/li>\n                            <\/ul>\n        <\/div>\n    <\/div>\n<\/div>\n            \n                <div class=\"item\">\n    <div class=\"item_wr\">\n                                <div class=\"item_thumbnail\">\n                <a href=\"https:\/\/www.amchambaq.com\/es_co\/events\/amcham-golf-tournament-2026\/\">\n                    <img decoding=\"async\" class=\"\" src=\"https:\/\/www.amchambaq.com\/wp-content\/uploads\/2026\/03\/AMCHAM-GOLF-2026-700x390.png\" width=\"700\" height=\"390\" alt=\"AMCHAM GOLF 2026\" title=\"AMCHAM GOLF 2026\" loading=\"lazy\" \/>                <\/a>\n            <\/div>\n                <div class=\"content\">\n            <h6><a href=\"https:\/\/www.amchambaq.com\/es_co\/events\/amcham-golf-tournament-2026\/\">AmCham Golf Tournament 2026<\/a><\/h6>\n            <ul class=\"stm-event__meta\">\n                                                   <li>\n                       <div class=\"event__calendar\">\n                            <i class=\"fa fa-calendar\" aria-hidden=\"true\"><\/i> abril 24, 2026                        <\/div>\n                    <\/li>\n                                                                                                <li>\n                            <div class=\"event__time\"><i class=\"fa fa-clock-o\"><\/i>\n                                6:00 am to 3:00 pm                            <\/div>\n                        <\/li>\n                                                                        <li>\n                        <div class=\"event__venue\">\n                            <i class=\"fa fa-map-marker\" aria-hidden=\"true\"><\/i> Barranquilla                        <\/div>\n                    <\/li>\n                            <\/ul>\n        <\/div>\n    <\/div>\n<\/div>\n                    <\/div>\n                    <\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid third_bg_color vc_custom_1484889309914\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner \"><div class=\"wpb_wrapper\">\n<section class=\"vc_cta3-container\" >\n    <div class=\"vc_general vc_cta3 third_bg_color vc_cta3-style-flat vc_cta3-shape-square vc_cta3-align-left vc_cta3-color-classic vc_cta3-icon-size-md vc_cta3-actions-right vc_custom_1540892243939 style=\"\"\">\n                        <div class=\"vc_cta3_content-container\">\n                                    <div class=\"vc_cta3-content\">\n                <header class=\"vc_cta3-content-header\">\n                    <div class=\"vc_custom_heading\" ><h2 style=\"font-size: 20px;color: #002e5b;line-height: 24px\" class=\"consulting-custom-title\">Looking for a First-Class Business Plan Consultant?<\/h2><\/div>                                    <\/header>\n                            <\/div>\n                        <div class=\"vc_cta3-actions\"><div class=\"vc_btn3-container vc_btn3-right vc_do_btn\" ><button class=\"vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-block vc_btn3-icon-right vc_btn3-color-theme_style_2\">get a quote <i class=\"vc_btn3-icon fa fa-chevron-right\"><\/i><\/button><\/div><\/div>        <\/div>\n                    <\/div>\n<\/section><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Descripci\u00f3n del Evento La C\u00e1mara de Comercio Colombo Americana\u00a0AmCham Atl\u00e1ntico &amp; Magdalena\u00a0te invita a participar en el tradicional AmCham Golf Tournament 2026. Una jornada para disfrutar del golf, conectar con l\u00edderes empresariales y vivir una gran experiencia dentro y fuera del campo. Viernes 24 de abril\u00a0 6:00 a.m. Club Lagos de Caujaral M\u00e1s info: comercial@amchambaq.com","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1530","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.amchambaq.com\/es_co\/wp-json\/wp\/v2\/pages\/1530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amchambaq.com\/es_co\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.amchambaq.com\/es_co\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.amchambaq.com\/es_co\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amchambaq.com\/es_co\/wp-json\/wp\/v2\/comments?post=1530"}],"version-history":[{"count":0,"href":"https:\/\/www.amchambaq.com\/es_co\/wp-json\/wp\/v2\/pages\/1530\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.amchambaq.com\/es_co\/wp-json\/wp\/v2\/media?parent=1530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}